{"id":127689,"date":"2021-02-16T14:23:49","date_gmt":"2021-02-16T12:23:49","guid":{"rendered":"https:\/\/concentrol.com\/antifoaming-agents-for-pressure-sensitive-adhesives\/"},"modified":"2021-02-16T16:39:29","modified_gmt":"2021-02-16T14:39:29","slug":"antiespumantes-para-adhesivos-sensibles-a-la-presion","status":"publish","type":"post","link":"https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/es\/antiespumantes-para-adhesivos-sensibles-a-la-presion\/","title":{"rendered":"Antiespumantes para adhesivos sensibles a la presi\u00f3n"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<span style=\"font-weight: 400;\">En Concentrol apostamos por la excelencia para ofrecer las mejores soluciones adaptadas a las necesidades de nuestros clientes. Nuestro equipo de t\u00e9cnicos y profesionales trabajan continuamente para ser pioneros en el sector.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En el siguiente art\u00edculo se recogen los estudios realizados en los laboratorios de Concentrol sobre los adhesivos (PSA) y presentamos la eficiencia de las soluciones\u00a0 EMULTROL DFM OLM-40 y EMULTROL DFM OLV-230 en comparaci\u00f3n a otras referencias de mercado.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>LOS ADHESIVOS SENSIBLES A LA PRESI\u00d3N (PSA) DE CONCENTROL<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Concentrol, a trav\u00e9s de su Divisi\u00f3n de Additives, trabaja en la elaboraci\u00f3n de productos para el sector de PSA. Los autoadhesivos (conocidos como Pressure sensitive adhesives o PSA por sus siglas en ingl\u00e9s) pueden unir una variedad de materiales tales como papeles, pl\u00e1sticos, metales, madera y vidrio. Como su nombre indica, son sensibles a la presi\u00f3n, en relaci\u00f3n a que enganchan en seco, a temperatura ambiente, con el simple contacto o una ligera presi\u00f3n, es decir, no requieren activaci\u00f3n por agua, solvente o calor.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dentro del amplio mundo de los autoadhesivos, el mercado de las etiquetas autoadhesivas representa un volumen enormemente grande y en crecimiento. Concentrol lleva a\u00f1os trabajando en dicho sector con el desarrollo y elaboraci\u00f3n de productos tales como: dispersiones de resinas, antiespumantes, emulsiones de cera, silicona y aditivos de superficie de silicona.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>\u00bfC\u00f3mo se fabrican?<\/b><\/p>\n<p><span style=\"font-weight: 400;\">El proceso de fabricaci\u00f3n de un autoadhesivo (PSA), consta de cuatro fases: siliconado, adhesivado, acondicionado y formaci\u00f3n del complejo. De forma resumida, se hace pasar el soporte (papel) por un cabezal donde se le a\u00f1ade la silicona, para obtener el papel siliconado. Posteriormente, este se introduce en otro cabezal donde se le a\u00f1ade el adhesivo y finalmente se le une una l\u00e1mina para formar el autoadhesivo propiamente dicho.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>El Siliconado<\/b><\/p>\n<p><span style=\"font-weight: 400;\">El siliconado consiste en aplicar una capa de silicona al papel soporte que nos permitir\u00e1 aplicar el adhesivo y transferirlo a la l\u00e1mina, protegiendo el adhesivo hasta su uso final y facilitando que la l\u00e1mina pueda despegarse f\u00e1cilmente del soporte. En definitiva, el siliconado nos permite dar al papel un tratamiento antiadherente para evitar que el soporte y la l\u00e1mina queden pegados entre s\u00ed.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La capa de siliconado que se aplica al soporte puede variar, dependiendo del mismo soporte y del producto final, aunque en general suele rondar los 1,1 a 1,3 g\/m2. Posteriormente el soporte (papel), ya siliconado, entra en un t\u00fanel de secado donde se realiza la reticulaci\u00f3n y polimerizaci\u00f3n a temperaturas muy elevadas.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>El adhesivado<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Es la fase en que se aplica el adhesivo al soporte siliconado. Posteriormente se realiza un secado para eliminar el agua o disolvente que contenga. La cantidad de adhesivo que aplica sobre el soporte oscila entre 10-25 g\/m2, dependiendo el uso final que se le vaya a dar.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>El acondicionado<\/b><\/p>\n<p><span style=\"font-weight: 400;\">En el acondicionamiento se realiza una operaci\u00f3n de reacondicionado de humedad al producto haci\u00e9ndolo pasar por una rampa de vapor a baja presi\u00f3n, ya que la humedad en las fases de siliconado y adhesivado puede producir efectos no deseados.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>La formaci\u00f3n del complejo<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Se trata de la \u00faltima fase del proceso y se lleva a cabo cuando se junta el soporte con la l\u00e1mina. Este proceso se produce cuando el adhesivo est\u00e1 suficientemente seco y el soporte tiene el grado de humedad necesario.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para juntar el soporte adhesivo con la l\u00e1mina, se hace pasar entre dos rodillos de contacto, quedando ambas capas adheridas. Debido a que el soporte tiene un tratamiento antiadherente obtenido por la silicona, el adhesivo queda \u00fanicamente pegado a la l\u00e1mina.<\/span><\/p>\n<h2><b>La Gama de adhesivos sensibles a la presi\u00f3n de Concentrol<\/b><\/h2>\n<p><b>Emulsiones de cera y silicona<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Las emulsiones de silicona normalmente contienen un componente de silicona (suele ser aceite de silicona), agua y los emulsionantes requeridos para obtener una emulsi\u00f3n estable. Desde la perspectiva qu\u00edmica, un componente de silicona es una cadena finita de \u00e1tomos de silicio y ox\u00edgeno unidos entre s\u00ed. Adem\u00e1s de estos enlaces, la propia silicona tiene otros dos enlaces a grupos org\u00e1nicos.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las microemulsiones de pol\u00edmeros de silicona est\u00e1n especialmente recomendadas para formulaciones de autoadhesivos y, tras su incorporaci\u00f3n en la formulaci\u00f3n, mejora el proceso de corte y troquelado de las bobinas de papel y film, especialmente a altas velocidades. Adem\u00e1s, debido a la humectaci\u00f3n de la superficie, mejoran la reolog\u00eda del PSA en rodillos. En dosis bajas no afecta negativamente la adhesi\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Son productos que ofrecen buenas caracter\u00edsticas: estabilidad t\u00e9rmica y de diluci\u00f3n, humectaci\u00f3n de la superficie, APEO Free, compatibilidad con jabones\/tensioactivos ani\u00f3nicos y no i\u00f3nicos, aplicaci\u00f3n f\u00e1cil, no amarillean despu\u00e9s de tiempo, y aportan caracter\u00edsticas mejoradas en el deslizamiento y la abrasi\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las emulsiones de cera permiten conseguir propiedades removibles y, en general, modificar la cohesi\u00f3n.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>Dispersiones de resina<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Las dispersiones de resina de Concentrol tienen como funci\u00f3n principal mejorar las propiedades de cohesi\u00f3n, tack y adhesi\u00f3n de autoadhesivos basados en dispersiones polim\u00e9ricas de resina acr\u00edlica, PVA, EVA, SBR, NBR, l\u00e1tex natural, policloropreno y dispersiones acuosas de poliuretano. Aumentan la adhesi\u00f3n y el tack en substratos no polares y superficies de baja energ\u00eda mejorando su capacidad de humectaci\u00f3n. Tambi\u00e9n pueden usarse en aplicaciones sobre soportes porosos y polares como el papel y el cart\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las dispersiones de resina de Concentrol ofrecen una serie de ventajas: APEO Free, I+D Flexible, lotes de fabricaci\u00f3n flexibles y productos aptos para contacto indirecto con alimentos.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>Antiespumantes<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Muchos de los adhesivos acr\u00edlicos base agua (PSA) tienden a generar espuma debido a su composici\u00f3n acuosa. La formaci\u00f3n de espuma puede ser un efecto indeseado,, tanto el proceso de formulaci\u00f3n del adhesivo como en el de su aplicaci\u00f3n. Aplicar una peque\u00f1a cantidad de antiespumante EMULTROL DFM OLM-40 de Concentrol, permite eliminar y prevenir la espuma en el adhesivo, con la m\u00e1xima compatibilidad, sin efectos adversos en el rendimiento de la dispersi\u00f3n y un efecto antiespumante perdurable en el tiempo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los antiespumantes son eficaces en dosis inferiores a 50-100 ppm de silicona activa, con efectos duraderos, actuando tanto como antiespumantes y como desaireantes. Est\u00e1n dise\u00f1ados para ser\u00a0 utilizados en aplicaciones con contacto directo en alimentos. Disponemos de soluciones que cumplen tanto la normativa Americana FDA 175.105<\/span><span style=\"font-weight: 400;\"> como la normativa Europea 10\/2011<\/span><span style=\"font-weight: 400;\">. ambas para adhesivos destinados al contacto alimentario. Los antiespumantes de Concentrol se dise\u00f1an APEO Free, mostr\u00e1ndose con un alto rendimiento, una buena eficacia y en definitiva un buen ratio precio\/eficacia.<\/span><\/p>\n<p><b>Aditivos de superficie de silicona<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Los aditivos de superficie de silicona son productos muy conocidos al ofrecer propiedades especiales en pinturas, tintas y recubrimientos. Estos aditivos son siliconas \u00f3rgano-funcionales, la mayor\u00eda de ellos compuestos de copol\u00edmeros de polisiloxano y poli\u00e9ter no hidrolizable.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nuestra gama de aditivos de superficie de silicona permite humectar mejor sin incrementar la generaci\u00f3n de espuma con dosis hasta diez veces inferiores a las de los humectantes tradicionales. Son la elecci\u00f3n correcta para formuladores que buscan mejorar deslizamiento, resistencia al desgaste, nivelaci\u00f3n, humectaci\u00f3n del sustrato, propiedades antibloqueo. Tambi\u00e9n pueden proporcionar acabados especiales, incrementar la suavidad de un recubrimiento, disminuir la fricci\u00f3n, mejorar la resistencia a la abrasi\u00f3n y rayado, etc. Son productos con APEO Free y un buen ratio precio\/eficacia.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>EMULTROL DFM OLM-40 y EMULTROL DFM OLV-230: soluciones sostenibles y eficientes<\/b><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Tal y como se ha mencionado anteriormente, en Concentrol apostamos por la creaci\u00f3n de soluciones competentes, de calidad, y que a la vez sean lo m\u00e1s sostenibles posible. Por ello, hemos dise\u00f1ado dos antiespumantes que cumplen esta serie de requisitos sin perder su eficiencia.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Nuestras soluciones<\/span><b> EMULTROL DFM OLM-40 y EMULTROL DFM OLV-230<\/b><span style=\"font-weight: 400;\"> son alternativas m\u00e1s sostenibles, que cumplen las regulaciones de contacto alimentario y mantienen la efectividad de otros antiespumantes del mercado que son realizados a partir de aceites minerales con un elevado contenido de compuestos org\u00e1nicos vol\u00e1tiles (VOC). Estos son m\u00e1s contaminantes y m\u00e1s agresivos para el medio ambiente. En cuanto a compuestos vol\u00e1tiles, por un lado <\/span><b>el EMULTROL DFM OLM-40<\/b><span style=\"font-weight: 400;\"> no contiene VOC, mientras que el EMULTROL DFM<\/span> <span style=\"font-weight: 400;\">OLV-230 no contiene VOC ni SVOC (cabe tener en cuenta que es el tipo de aceite utilizado el que diferencia si un antiespumante cumple con las regulaciones del contacto alimentario o no).<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">La primera referencia, <\/span><b>EMULTROL DFM<\/b> <b>OLM-40,<\/b><span style=\"font-weight: 400;\"> est\u00e1 compuesta a base de aceite mineral blanco, con materia 100% activa y libre de VOC. Su uso principal se dirige a la fabricaci\u00f3n de adhesivos sensibles a la presi\u00f3n y presenta una excelente compatibilidad con las formulaciones habituales.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Por lo que se refiere a <\/span><b>EMULTROL DFM<\/b> <b>OLV-230<\/b><span style=\"font-weight: 400;\">, es elaborado a base de aceites vegetales modificados, factor que le convierte en un producto biodegradable, libre de VOC y SVOC. En gran medida su aplicaci\u00f3n va destinada a la fabricaci\u00f3n de adhesivos sensibles a la presi\u00f3n y presenta una excelente compatibilidad con formulaciones habituales.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Por lo que se refiere a<\/span><b> EMULTROL DFM<\/b> <b>OLV-230<\/b><span style=\"font-weight: 400;\">, es elaborado a base de <\/span><b>aceite vegetal<\/b><span style=\"font-weight: 400;\">, factor que le convierte en un producto <\/span><b>biodegradable<\/b><span style=\"font-weight: 400;\">, <\/span><b>libre de VOC y SVOC<\/b><span style=\"font-weight: 400;\">, <\/span><b>con etiqueta ecol\u00f3gica de la UE n. \u00b0 312\/2014<\/b><span style=\"font-weight: 400;\">. En gran medida su aplicaci\u00f3n va destinada a la fabricaci\u00f3n de adhesivos sensibles a la presi\u00f3n y presenta una excelente compatibilidad con formulaciones habituales.<\/span><\/p>\n<p>&nbsp;<\/p>\n<table>\n<tbody>\n<tr>\n<td><b>EMULTROL DFM OLM-40<\/b><\/td>\n<td><b>EMULTROL DFM OLV-230<\/b><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400;\">Basado en aceite mineral blanco<\/span><\/td>\n<td><span style=\"font-weight: 400;\">Basado en aceite vegetal (biodegradable)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400;\">Materia 100% activa<\/span><\/td>\n<td><span style=\"font-weight: 400;\">Materia 100% activa<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400;\">Excelente compatibilidad con formulaciones habituales.<\/span><\/td>\n<td><span style=\"font-weight: 400;\">Excelente compatibilidad con formulaciones habituales.<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400;\">Dosis recomendada: 0,1 &#8211; 0,5% sobre la formulaci\u00f3n total.<\/span><\/td>\n<td><span style=\"font-weight: 400;\">Dosis recomendada: 0,1 &#8211; 0,5% sobre la formulaci\u00f3n total.<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400;\">Contacto con alimentos: T\u00edtulo 21 CFR (FDA): 175.105, 176.210.<\/span><\/td>\n<td><span style=\"font-weight: 400;\">Contacto con alimentos: Reglamento UE No 10\/2011; T\u00edtulo 21 CFR (FDA): 175.105, 176.210 (papel y cart\u00f3n)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400;\">Libre de COV<\/span><\/td>\n<td><span style=\"font-weight: 400;\">Libre de VOC y SVOC. Reglamento de la etiqueta ecol\u00f3gica de la UE n. \u00b0 312\/2014.<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400;\">Aplicaci\u00f3n principal: Fabricaci\u00f3n de adhesivos sensibles a la presi\u00f3n.<\/span><\/td>\n<td><span style=\"font-weight: 400;\">Aplicaci\u00f3n principal: Fabricaci\u00f3n de adhesivos sensibles a la presi\u00f3n.<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><i><span style=\"font-weight: 400;\">Tabla 1: comparativa entre las caracter\u00edsticas y propiedades de EMULTROL DMF OLM-40 y EMULTROL DMF OLV-230<\/span><\/i><\/p>\n<p>&nbsp;<\/p>\n<p><b>EMULTROL DFM OLV-230<\/b><span style=\"font-weight: 400;\">, al ser compuesto a base de aceite vegetal modificado, tiene un importante punto a favor para su uso: es m\u00e1s sostenible que los antiespumantes basados en aceite mineral. Aunque los antiespumantes derivados del petr\u00f3leo suelen ser soluciones m\u00e1s econ\u00f3micas, <\/span><b>en muchos casos se trata de productos virtualmente t\u00f3xicos y que contienen elevadas cantidades de VOC y SVOC.<\/b><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Precisamente, la <\/span><b>Comisi\u00f3n Europea<\/b><span style=\"font-weight: 400;\"> inici\u00f3 unos procesos de evaluaci\u00f3n alrededor de los riesgos que presentan los antiespumantes derivados del petr\u00f3leo, declarando la necesidad de declarar la presencia de aceites minerales en multitud de productos alimentarios.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por este motivo, apostar por productos como <\/span><b>EMULTROL DFM OLV-230<\/b><span style=\"font-weight: 400;\">, <\/span><b>biodegradables y libres de agentes contaminantes<\/b><span style=\"font-weight: 400;\">, es un requerimiento cada vez m\u00e1s importante. A la vez, estas soluciones poseen <\/span><b>la misma eficacia que los productos tradicionales, conservando su alta capacidad de eliminar la espuma y prevenir defectos e irregularidades del producto final.\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Desde Concentrol trabajamos para desarrollar las mejores soluciones para nuestros clientes. Bajo la finalidad de ofrecer el mejor producto posible con la mejor relaci\u00f3n calidad-precio del mercado, teniendo en cuenta la materia fundamental de la sostenibilidad, elaboramos soluciones en nuestros laboratorios y apostamos por el I+D d\u00eda tras d\u00eda.<\/span>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/1&#8243;][vc_button border_width=\u00bb0&#8243; link=\u00bburl:https%3A%2F%2Fconcentrol.com%2Fwp-content%2Fuploads%2F2021%2F02%2FES_OLM-40-OLV-23.pdf\u00bb]Descargar infogr\u00e1fico[\/vc_button][vc_column_text]<div class=\"wp-block-pdfemb-pdf-embedder-viewer\"><a href=\"https:\/\/concentrol.com\/wp-content\/uploads\/2021\/02\/ES_OLM-40-OLV-23.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"bottom\" data-toolbar-fixed=\"off\">ES_OLM-40-OLV-23<\/a><\/div>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]En Concentrol apostamos por la excelencia para ofrecer las mejores soluciones adaptadas a las necesidades de nuestros clientes. Nuestro equipo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":127649,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[197],"tags":[710],"class_list":["post-127689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-additives-es-2","tag-adhesives-pressure-ca-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Antiespumantes para adhesivos sensibles a la presi\u00f3n<\/title>\n<meta name=\"description\" content=\"Concentrol - Chemical Solutions\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/concentrol.com\/es\/antiespumantes-para-adhesivos-sensibles-a-la-presion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Antiespumantes para adhesivos sensibles a la presi\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Concentrol - Chemical Solutions\" \/>\n<meta property=\"og:url\" content=\"https:\/\/concentrol.com\/es\/antiespumantes-para-adhesivos-sensibles-a-la-presion\/\" \/>\n<meta property=\"og:site_name\" content=\"Concentrol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/concentrol\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-16T12:23:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-16T14:39:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/concentrol.com\/wp-content\/uploads\/2021\/02\/Concentrol-OLM-OLV-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Concentrol\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@concentrol\" \/>\n<meta name=\"twitter:site\" content=\"@concentrol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Concentrol\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/concentrol.com\\\/es\\\/antiespumantes-para-adhesivos-sensibles-a-la-presion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/concentrol.com\\\/es\\\/antiespumantes-para-adhesivos-sensibles-a-la-presion\\\/\"},\"author\":{\"name\":\"Concentrol\",\"@id\":\"https:\\\/\\\/concentrol.com\\\/de\\\/#\\\/schema\\\/person\\\/38ca1533353df1701137f175f8ec8dd0\"},\"headline\":\"Antiespumantes para adhesivos sensibles a la presi\u00f3n\",\"datePublished\":\"2021-02-16T12:23:49+00:00\",\"dateModified\":\"2021-02-16T14:39:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/concentrol.com\\\/es\\\/antiespumantes-para-adhesivos-sensibles-a-la-presion\\\/\"},\"wordCount\":2021,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/concentrol.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/concentrol.com\\\/es\\\/antiespumantes-para-adhesivos-sensibles-a-la-presion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hosting175685eu-cp704.wordpresstemporal.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Concentrol-OLM-OLV-scaled.jpg\",\"keywords\":[\"Adhesives-pressure\"],\"articleSection\":[\"ADDITIVES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/concentrol.com\\\/es\\\/antiespumantes-para-adhesivos-sensibles-a-la-presion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/concentrol.com\\\/es\\\/antiespumantes-para-adhesivos-sensibles-a-la-presion\\\/\",\"url\":\"https:\\\/\\\/concentrol.com\\\/es\\\/antiespumantes-para-adhesivos-sensibles-a-la-presion\\\/\",\"name\":\"Antiespumantes para adhesivos sensibles a la presi\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/concentrol.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/concentrol.com\\\/es\\\/antiespumantes-para-adhesivos-sensibles-a-la-presion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/concentrol.com\\\/es\\\/antiespumantes-para-adhesivos-sensibles-a-la-presion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hosting175685eu-cp704.wordpresstemporal.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Concentrol-OLM-OLV-scaled.jpg\",\"datePublished\":\"2021-02-16T12:23:49+00:00\",\"dateModified\":\"2021-02-16T14:39:29+00:00\",\"description\":\"Concentrol - Chemical Solutions\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/concentrol.com\\\/es\\\/antiespumantes-para-adhesivos-sensibles-a-la-presion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/concentrol.com\\\/es\\\/antiespumantes-para-adhesivos-sensibles-a-la-presion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/concentrol.com\\\/es\\\/antiespumantes-para-adhesivos-sensibles-a-la-presion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hosting175685eu-cp704.wordpresstemporal.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Concentrol-OLM-OLV-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/hosting175685eu-cp704.wordpresstemporal.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Concentrol-OLM-OLV-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/concentrol.com\\\/es\\\/antiespumantes-para-adhesivos-sensibles-a-la-presion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/concentrol.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Antiespumantes para adhesivos sensibles a la presi\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/concentrol.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/concentrol.com\\\/de\\\/\",\"name\":\"Concentrol\",\"description\":\"Chemical Solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/concentrol.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/concentrol.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/concentrol.com\\\/de\\\/#organization\",\"name\":\"Productos Concentrol, S.A.\",\"url\":\"https:\\\/\\\/concentrol.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/concentrol.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/concentrol.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/logo_ok-01.png\",\"contentUrl\":\"https:\\\/\\\/concentrol.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/logo_ok-01.png\",\"width\":1354,\"height\":1018,\"caption\":\"Productos Concentrol, S.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/concentrol.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/concentrol\\\/\",\"https:\\\/\\\/x.com\\\/concentrol\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/concentrol\\\/\",\"https:\\\/\\\/www.instagram.com\\\/concentrol_com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCHRBaGs_viVptdVzPr6QF3A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/concentrol.com\\\/de\\\/#\\\/schema\\\/person\\\/38ca1533353df1701137f175f8ec8dd0\",\"name\":\"Concentrol\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04da71c36ba92a54c0ca824812c5b01d9eab26e2fdb073f0bdde4471b481917?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04da71c36ba92a54c0ca824812c5b01d9eab26e2fdb073f0bdde4471b481917?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d04da71c36ba92a54c0ca824812c5b01d9eab26e2fdb073f0bdde4471b481917?s=96&d=mm&r=g\",\"caption\":\"Concentrol\"},\"url\":\"https:\\\/\\\/hosting175685eu-cp704.wordpresstemporal.com\\\/es\\\/author\\\/adminconcentrol\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Antiespumantes para adhesivos sensibles a la presi\u00f3n","description":"Concentrol - Chemical Solutions","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/concentrol.com\/es\/antiespumantes-para-adhesivos-sensibles-a-la-presion\/","og_locale":"es_ES","og_type":"article","og_title":"Antiespumantes para adhesivos sensibles a la presi\u00f3n","og_description":"Concentrol - Chemical Solutions","og_url":"https:\/\/concentrol.com\/es\/antiespumantes-para-adhesivos-sensibles-a-la-presion\/","og_site_name":"Concentrol","article_publisher":"https:\/\/www.facebook.com\/concentrol\/","article_published_time":"2021-02-16T12:23:49+00:00","article_modified_time":"2021-02-16T14:39:29+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/concentrol.com\/wp-content\/uploads\/2021\/02\/Concentrol-OLM-OLV-scaled.jpg","type":"image\/jpeg"}],"author":"Concentrol","twitter_card":"summary_large_image","twitter_creator":"@concentrol","twitter_site":"@concentrol","twitter_misc":{"Escrito por":"Concentrol","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/concentrol.com\/es\/antiespumantes-para-adhesivos-sensibles-a-la-presion\/#article","isPartOf":{"@id":"https:\/\/concentrol.com\/es\/antiespumantes-para-adhesivos-sensibles-a-la-presion\/"},"author":{"name":"Concentrol","@id":"https:\/\/concentrol.com\/de\/#\/schema\/person\/38ca1533353df1701137f175f8ec8dd0"},"headline":"Antiespumantes para adhesivos sensibles a la presi\u00f3n","datePublished":"2021-02-16T12:23:49+00:00","dateModified":"2021-02-16T14:39:29+00:00","mainEntityOfPage":{"@id":"https:\/\/concentrol.com\/es\/antiespumantes-para-adhesivos-sensibles-a-la-presion\/"},"wordCount":2021,"commentCount":0,"publisher":{"@id":"https:\/\/concentrol.com\/de\/#organization"},"image":{"@id":"https:\/\/concentrol.com\/es\/antiespumantes-para-adhesivos-sensibles-a-la-presion\/#primaryimage"},"thumbnailUrl":"https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/wp-content\/uploads\/2021\/02\/Concentrol-OLM-OLV-scaled.jpg","keywords":["Adhesives-pressure"],"articleSection":["ADDITIVES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/concentrol.com\/es\/antiespumantes-para-adhesivos-sensibles-a-la-presion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/concentrol.com\/es\/antiespumantes-para-adhesivos-sensibles-a-la-presion\/","url":"https:\/\/concentrol.com\/es\/antiespumantes-para-adhesivos-sensibles-a-la-presion\/","name":"Antiespumantes para adhesivos sensibles a la presi\u00f3n","isPartOf":{"@id":"https:\/\/concentrol.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/concentrol.com\/es\/antiespumantes-para-adhesivos-sensibles-a-la-presion\/#primaryimage"},"image":{"@id":"https:\/\/concentrol.com\/es\/antiespumantes-para-adhesivos-sensibles-a-la-presion\/#primaryimage"},"thumbnailUrl":"https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/wp-content\/uploads\/2021\/02\/Concentrol-OLM-OLV-scaled.jpg","datePublished":"2021-02-16T12:23:49+00:00","dateModified":"2021-02-16T14:39:29+00:00","description":"Concentrol - Chemical Solutions","breadcrumb":{"@id":"https:\/\/concentrol.com\/es\/antiespumantes-para-adhesivos-sensibles-a-la-presion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/concentrol.com\/es\/antiespumantes-para-adhesivos-sensibles-a-la-presion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/concentrol.com\/es\/antiespumantes-para-adhesivos-sensibles-a-la-presion\/#primaryimage","url":"https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/wp-content\/uploads\/2021\/02\/Concentrol-OLM-OLV-scaled.jpg","contentUrl":"https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/wp-content\/uploads\/2021\/02\/Concentrol-OLM-OLV-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/concentrol.com\/es\/antiespumantes-para-adhesivos-sensibles-a-la-presion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/concentrol.com\/es\/"},{"@type":"ListItem","position":2,"name":"Antiespumantes para adhesivos sensibles a la presi\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/concentrol.com\/de\/#website","url":"https:\/\/concentrol.com\/de\/","name":"Concentrol","description":"Chemical Solutions","publisher":{"@id":"https:\/\/concentrol.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/concentrol.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/concentrol.com\/de\/#organization","name":"Productos Concentrol, S.A.","url":"https:\/\/concentrol.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/concentrol.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/concentrol.com\/wp-content\/uploads\/2019\/10\/logo_ok-01.png","contentUrl":"https:\/\/concentrol.com\/wp-content\/uploads\/2019\/10\/logo_ok-01.png","width":1354,"height":1018,"caption":"Productos Concentrol, S.A."},"image":{"@id":"https:\/\/concentrol.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/concentrol\/","https:\/\/x.com\/concentrol","https:\/\/www.linkedin.com\/company\/concentrol\/","https:\/\/www.instagram.com\/concentrol_com\/","https:\/\/www.youtube.com\/channel\/UCHRBaGs_viVptdVzPr6QF3A"]},{"@type":"Person","@id":"https:\/\/concentrol.com\/de\/#\/schema\/person\/38ca1533353df1701137f175f8ec8dd0","name":"Concentrol","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d04da71c36ba92a54c0ca824812c5b01d9eab26e2fdb073f0bdde4471b481917?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d04da71c36ba92a54c0ca824812c5b01d9eab26e2fdb073f0bdde4471b481917?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d04da71c36ba92a54c0ca824812c5b01d9eab26e2fdb073f0bdde4471b481917?s=96&d=mm&r=g","caption":"Concentrol"},"url":"https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/es\/author\/adminconcentrol\/"}]}},"rttpg_featured_image_url":{"full":["https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/wp-content\/uploads\/2021\/02\/Concentrol-OLM-OLV-scaled.jpg",2560,1707,false],"landscape":["https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/wp-content\/uploads\/2021\/02\/Concentrol-OLM-OLV-scaled.jpg",2560,1707,false],"portraits":["https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/wp-content\/uploads\/2021\/02\/Concentrol-OLM-OLV-scaled.jpg",2560,1707,false],"thumbnail":["https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/wp-content\/uploads\/2021\/02\/Concentrol-OLM-OLV-150x150.jpg",150,150,true],"medium":["https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/wp-content\/uploads\/2021\/02\/Concentrol-OLM-OLV-300x200.jpg",300,200,true],"large":["https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/wp-content\/uploads\/2021\/02\/Concentrol-OLM-OLV-1024x683.jpg",840,560,true],"1536x1536":["https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/wp-content\/uploads\/2021\/02\/Concentrol-OLM-OLV-1536x1024.jpg",1536,1024,true],"2048x2048":["https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/wp-content\/uploads\/2021\/02\/Concentrol-OLM-OLV-2048x1365.jpg",2048,1365,true],"uncode_woocommerce_nav_thumbnail_regular":["https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/wp-content\/uploads\/2021\/02\/Concentrol-OLM-OLV-scaled.jpg",350,233,false],"uncode_woocommerce_nav_thumbnail_crop":["https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/wp-content\/uploads\/2021\/02\/Concentrol-OLM-OLV-scaled.jpg",348,232,false],"menu-thumb":["https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/wp-content\/uploads\/2021\/02\/Concentrol-OLM-OLV-scaled.jpg",330,220,false],"woocommerce_thumbnail":["https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/wp-content\/uploads\/2021\/02\/Concentrol-OLM-OLV-scaled-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/wp-content\/uploads\/2021\/02\/Concentrol-OLM-OLV-scaled.jpg",600,400,false],"woocommerce_gallery_thumbnail":["https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/wp-content\/uploads\/2021\/02\/Concentrol-OLM-OLV-scaled-100x100.jpg",100,100,true],"rp4wp-thumbnail-post":["https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/wp-content\/uploads\/2021\/02\/Concentrol-OLM-OLV-150x150.jpg",150,150,true]},"rttpg_author":{"display_name":"Concentrol","author_link":"https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/es\/author\/adminconcentrol\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/es\/category\/research-blog-es\/additives-es-2\/\" rel=\"category tag\">ADDITIVES<\/a>","rttpg_excerpt":"[vc_row][vc_column][vc_column_text]En Concentrol apostamos por la excelencia para ofrecer las mejores soluciones adaptadas a las necesidades de nuestros clientes. Nuestro equipo [&hellip;]","_links":{"self":[{"href":"https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/es\/wp-json\/wp\/v2\/posts\/127689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/es\/wp-json\/wp\/v2\/comments?post=127689"}],"version-history":[{"count":0,"href":"https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/es\/wp-json\/wp\/v2\/posts\/127689\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/es\/wp-json\/wp\/v2\/media\/127649"}],"wp:attachment":[{"href":"https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/es\/wp-json\/wp\/v2\/media?parent=127689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/es\/wp-json\/wp\/v2\/categories?post=127689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hosting175685eu-cp704.wordpresstemporal.com\/es\/wp-json\/wp\/v2\/tags?post=127689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}